{"id":30745,"date":"2022-06-16T10:15:16","date_gmt":"2022-06-16T08:15:16","guid":{"rendered":"https:\/\/www.valpiccola.it\/?p=30745"},"modified":"2022-06-16T10:15:17","modified_gmt":"2022-06-16T08:15:17","slug":"sconto-luglio","status":"publish","type":"post","link":"https:\/\/www.valpiccola.it\/en\/2022\/06\/16\/sconto-luglio\/","title":{"rendered":"Sconto luglio!"},"content":{"rendered":"\n<p>Prenota un soggiorno dal 2 al 16 luglio e ottieni un 10% di sconto. Contattaci!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prenota un soggiorno dal 2 al 16 luglio e ottieni un 10% di<\/p>\n","protected":false},"author":1001008,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[22],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sconto luglio! - Residence Valpiccola<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.valpiccola.it\/en\/2022\/06\/16\/sconto-luglio\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alessandro De Peron\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.valpiccola.it\/en\/2022\/06\/16\/sconto-luglio\/\",\"url\":\"https:\/\/www.valpiccola.it\/en\/2022\/06\/16\/sconto-luglio\/\",\"name\":\"Sconto luglio! - Residence Valpiccola\",\"isPartOf\":{\"@id\":\"https:\/\/www.valpiccola.it\/en\/#website\"},\"datePublished\":\"2022-06-16T08:15:16+00:00\",\"dateModified\":\"2022-06-16T08:15:17+00:00\",\"author\":{\"@id\":\"https:\/\/www.valpiccola.it\/en\/#\/schema\/person\/3f3b618e7dabab3a7fa1abbce127cba4\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.valpiccola.it\/en\/2022\/06\/16\/sconto-luglio\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.valpiccola.it\/en\/#website\",\"url\":\"https:\/\/www.valpiccola.it\/en\/\",\"name\":\"Residence Valpiccola\",\"description\":\"Holydays in the Dolomites  in val di Zoldo - Apartments, Residence, Garni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.valpiccola.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.valpiccola.it\/en\/#\/schema\/person\/3f3b618e7dabab3a7fa1abbce127cba4\",\"name\":\"Alessandro De Peron\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.valpiccola.it\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7e9c082e9c56c325ed635959a11cba57?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7e9c082e9c56c325ed635959a11cba57?s=96&d=mm&r=g\",\"caption\":\"Alessandro De Peron\"},\"url\":\"https:\/\/www.valpiccola.it\/en\/author\/ale-de-peron\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sconto luglio! - Residence Valpiccola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valpiccola.it\/en\/2022\/06\/16\/sconto-luglio\/","twitter_misc":{"Written by":"Alessandro De Peron","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.valpiccola.it\/en\/2022\/06\/16\/sconto-luglio\/","url":"https:\/\/www.valpiccola.it\/en\/2022\/06\/16\/sconto-luglio\/","name":"Sconto luglio! - Residence Valpiccola","isPartOf":{"@id":"https:\/\/www.valpiccola.it\/en\/#website"},"datePublished":"2022-06-16T08:15:16+00:00","dateModified":"2022-06-16T08:15:17+00:00","author":{"@id":"https:\/\/www.valpiccola.it\/en\/#\/schema\/person\/3f3b618e7dabab3a7fa1abbce127cba4"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valpiccola.it\/en\/2022\/06\/16\/sconto-luglio\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.valpiccola.it\/en\/#website","url":"https:\/\/www.valpiccola.it\/en\/","name":"Residence Valpiccola","description":"Holydays in the Dolomites  in val di Zoldo - Apartments, Residence, Garni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valpiccola.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.valpiccola.it\/en\/#\/schema\/person\/3f3b618e7dabab3a7fa1abbce127cba4","name":"Alessandro De Peron","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.valpiccola.it\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7e9c082e9c56c325ed635959a11cba57?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e9c082e9c56c325ed635959a11cba57?s=96&d=mm&r=g","caption":"Alessandro De Peron"},"url":"https:\/\/www.valpiccola.it\/en\/author\/ale-de-peron\/"}]}},"_links":{"self":[{"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/posts\/30745"}],"collection":[{"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/users\/1001008"}],"replies":[{"embeddable":true,"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/comments?post=30745"}],"version-history":[{"count":1,"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/posts\/30745\/revisions"}],"predecessor-version":[{"id":30746,"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/posts\/30745\/revisions\/30746"}],"wp:attachment":[{"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/media?parent=30745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/categories?post=30745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/tags?post=30745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}