{"id":2824,"date":"2015-03-17T17:01:48","date_gmt":"2015-03-17T15:01:48","guid":{"rendered":"https:\/\/www.valpiccola.it\/?p=2824"},"modified":"2015-03-17T17:01:48","modified_gmt":"2015-03-17T15:01:48","slug":"speciale-pasqua","status":"publish","type":"post","link":"https:\/\/www.valpiccola.it\/en\/2015\/03\/17\/speciale-pasqua\/","title":{"rendered":"Speciale Pasqua"},"content":{"rendered":"<p>Il nostro residence rimarr\u00e0 aperto anche nel periodo di Pasqua! Viste le recenti nevicate cosa ne dite di provare una vacanza sulla neve primaverile? Giornate lunghe e piene di divertimento vi aspettano&#8230; Per maggiori info inviateci una mail a info@valpiccola.it oppure chiamateci al 0437 788827.<\/p>\n<p><a href=\"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/10\/slide2.jpg\"><img decoding=\"async\" class=\"alignnone  wp-image-2264\" src=\"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/10\/slide2-300x100.jpg\" alt=\"slide2\" width=\"384\" height=\"128\" srcset=\"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/10\/slide2-300x100.jpg 300w, https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/10\/slide2-1024x341.jpg 1024w, https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/10\/slide2.jpg 1200w\" sizes=\"(max-width: 384px) 100vw, 384px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il nostro residence rimarr\u00e0 aperto anche nel periodo di Pasqua! Viste le recenti<\/p>\n","protected":false},"author":1001003,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[15],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Speciale Pasqua - Residence Valpiccola<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.valpiccola.it\/en\/2015\/03\/17\/speciale-pasqua\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianni Nobile\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.valpiccola.it\/en\/2015\/03\/17\/speciale-pasqua\/\",\"url\":\"https:\/\/www.valpiccola.it\/en\/2015\/03\/17\/speciale-pasqua\/\",\"name\":\"Speciale Pasqua - Residence Valpiccola\",\"isPartOf\":{\"@id\":\"https:\/\/www.valpiccola.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.valpiccola.it\/en\/2015\/03\/17\/speciale-pasqua\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.valpiccola.it\/en\/2015\/03\/17\/speciale-pasqua\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/10\/slide2-300x100.jpg\",\"datePublished\":\"2015-03-17T15:01:48+00:00\",\"dateModified\":\"2015-03-17T15:01:48+00:00\",\"author\":{\"@id\":\"https:\/\/www.valpiccola.it\/en\/#\/schema\/person\/290c27b7ec1ff98c207848f3e27dd912\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.valpiccola.it\/en\/2015\/03\/17\/speciale-pasqua\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.valpiccola.it\/en\/2015\/03\/17\/speciale-pasqua\/#primaryimage\",\"url\":\"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/10\/slide2-300x100.jpg\",\"contentUrl\":\"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/10\/slide2-300x100.jpg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.valpiccola.it\/en\/#website\",\"url\":\"https:\/\/www.valpiccola.it\/en\/\",\"name\":\"Residence Valpiccola\",\"description\":\"Holydays in the Dolomites  in val di Zoldo - Apartments, Residence, Garni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.valpiccola.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.valpiccola.it\/en\/#\/schema\/person\/290c27b7ec1ff98c207848f3e27dd912\",\"name\":\"Gianni Nobile\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.valpiccola.it\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a580b3bd64279503e913ad1edd9f52f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a580b3bd64279503e913ad1edd9f52f7?s=96&d=mm&r=g\",\"caption\":\"Gianni Nobile\"},\"url\":\"https:\/\/www.valpiccola.it\/en\/author\/gianni-nobile-2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Speciale Pasqua - Residence Valpiccola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valpiccola.it\/en\/2015\/03\/17\/speciale-pasqua\/","twitter_misc":{"Written by":"Gianni Nobile"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.valpiccola.it\/en\/2015\/03\/17\/speciale-pasqua\/","url":"https:\/\/www.valpiccola.it\/en\/2015\/03\/17\/speciale-pasqua\/","name":"Speciale Pasqua - Residence Valpiccola","isPartOf":{"@id":"https:\/\/www.valpiccola.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valpiccola.it\/en\/2015\/03\/17\/speciale-pasqua\/#primaryimage"},"image":{"@id":"https:\/\/www.valpiccola.it\/en\/2015\/03\/17\/speciale-pasqua\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/10\/slide2-300x100.jpg","datePublished":"2015-03-17T15:01:48+00:00","dateModified":"2015-03-17T15:01:48+00:00","author":{"@id":"https:\/\/www.valpiccola.it\/en\/#\/schema\/person\/290c27b7ec1ff98c207848f3e27dd912"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valpiccola.it\/en\/2015\/03\/17\/speciale-pasqua\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.valpiccola.it\/en\/2015\/03\/17\/speciale-pasqua\/#primaryimage","url":"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/10\/slide2-300x100.jpg","contentUrl":"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/10\/slide2-300x100.jpg"},{"@type":"WebSite","@id":"https:\/\/www.valpiccola.it\/en\/#website","url":"https:\/\/www.valpiccola.it\/en\/","name":"Residence Valpiccola","description":"Holydays in the Dolomites  in val di Zoldo - Apartments, Residence, Garni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valpiccola.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.valpiccola.it\/en\/#\/schema\/person\/290c27b7ec1ff98c207848f3e27dd912","name":"Gianni Nobile","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.valpiccola.it\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a580b3bd64279503e913ad1edd9f52f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a580b3bd64279503e913ad1edd9f52f7?s=96&d=mm&r=g","caption":"Gianni Nobile"},"url":"https:\/\/www.valpiccola.it\/en\/author\/gianni-nobile-2\/"}]}},"_links":{"self":[{"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/posts\/2824"}],"collection":[{"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/users\/1001003"}],"replies":[{"embeddable":true,"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/comments?post=2824"}],"version-history":[{"count":1,"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/posts\/2824\/revisions"}],"predecessor-version":[{"id":2825,"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/posts\/2824\/revisions\/2825"}],"wp:attachment":[{"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/media?parent=2824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/categories?post=2824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/tags?post=2824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}