{"id":1356,"date":"2014-07-23T16:34:41","date_gmt":"2014-07-23T14:34:41","guid":{"rendered":"https:\/\/www.valpiccola.it\/?p=1356"},"modified":"2014-07-23T16:34:41","modified_gmt":"2014-07-23T14:34:41","slug":"slackline-paradise","status":"publish","type":"post","link":"https:\/\/www.valpiccola.it\/en\/2014\/07\/23\/slackline-paradise\/","title":{"rendered":"Slackline Paradise!"},"content":{"rendered":"<p>Domenica 3 Agosto si terr\u00e0 al Rifugio Su\u2019n Paradis, di Zoldo Alto (BL) il primo SLACKLINE PARADISE &#8211; Slackline Party.<\/p>\n<p>SLACKLINE PARADISE sar\u00e0 una giornata di festa durante la quale potrete praticare un po&#8217; di slackline (anche per chi non ha mai provato prima), ammirare chi \u00e8 perfettamente a suo agio nel camminare e trikkeggiare a diversi metri da terra, oppure semplicemente mangiare e bere qualcosa, e fare quattro chiacchiere ascoltando dell&#8217;ottima musica.<br \/>\nIl tutto sar\u00e0 accompagnato da uno slip&#8217;n&#8217;slide (scivolo saponato) lungo 50m, dalla possibilit\u00e0 da girare con MTB a noleggio con guida a prezzi simbolici, dal campeggio libero (sabato e domenica), dal rifugio aperto anche a cena, dal consueto lancio di gadget che contraddistingue Superpark&#8230;<br \/>\nNon dimenticatevi che potrete vivere le cose sopraelencate nello splendido contesto delle Dolomiti Zoldane, il che non \u00e8 poca cosa!<\/p>\n<p>Non vi resta che venire a vedere. Vi aspettiamo!<\/p>\n<p><a href=\"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/07\/Banner_FB_event-600x222.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-1357\" src=\"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/07\/Banner_FB_event-600x222.jpg\" alt=\"Print\" width=\"600\" height=\"222\" srcset=\"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/07\/Banner_FB_event-600x222.jpg 600w, https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/07\/Banner_FB_event-600x222-300x111.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domenica 3 Agosto si terr\u00e0 al Rifugio Su\u2019n Paradis, di Zoldo Alto (BL)<\/p>\n","protected":false},"author":1001003,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[15],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Slackline Paradise! - Residence Valpiccola<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.valpiccola.it\/en\/2014\/07\/23\/slackline-paradise\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianni Nobile\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.valpiccola.it\/en\/2014\/07\/23\/slackline-paradise\/\",\"url\":\"https:\/\/www.valpiccola.it\/en\/2014\/07\/23\/slackline-paradise\/\",\"name\":\"Slackline Paradise! - Residence Valpiccola\",\"isPartOf\":{\"@id\":\"https:\/\/www.valpiccola.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.valpiccola.it\/en\/2014\/07\/23\/slackline-paradise\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.valpiccola.it\/en\/2014\/07\/23\/slackline-paradise\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/07\/Banner_FB_event-600x222.jpg\",\"datePublished\":\"2014-07-23T14:34:41+00:00\",\"dateModified\":\"2014-07-23T14:34:41+00:00\",\"author\":{\"@id\":\"https:\/\/www.valpiccola.it\/en\/#\/schema\/person\/290c27b7ec1ff98c207848f3e27dd912\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.valpiccola.it\/en\/2014\/07\/23\/slackline-paradise\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.valpiccola.it\/en\/2014\/07\/23\/slackline-paradise\/#primaryimage\",\"url\":\"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/07\/Banner_FB_event-600x222.jpg\",\"contentUrl\":\"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/07\/Banner_FB_event-600x222.jpg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.valpiccola.it\/en\/#website\",\"url\":\"https:\/\/www.valpiccola.it\/en\/\",\"name\":\"Residence Valpiccola\",\"description\":\"Holydays in the Dolomites  in val di Zoldo - Apartments, Residence, Garni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.valpiccola.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.valpiccola.it\/en\/#\/schema\/person\/290c27b7ec1ff98c207848f3e27dd912\",\"name\":\"Gianni Nobile\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.valpiccola.it\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a580b3bd64279503e913ad1edd9f52f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a580b3bd64279503e913ad1edd9f52f7?s=96&d=mm&r=g\",\"caption\":\"Gianni Nobile\"},\"url\":\"https:\/\/www.valpiccola.it\/en\/author\/gianni-nobile-2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Slackline Paradise! - Residence Valpiccola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valpiccola.it\/en\/2014\/07\/23\/slackline-paradise\/","twitter_misc":{"Written by":"Gianni Nobile","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.valpiccola.it\/en\/2014\/07\/23\/slackline-paradise\/","url":"https:\/\/www.valpiccola.it\/en\/2014\/07\/23\/slackline-paradise\/","name":"Slackline Paradise! - Residence Valpiccola","isPartOf":{"@id":"https:\/\/www.valpiccola.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valpiccola.it\/en\/2014\/07\/23\/slackline-paradise\/#primaryimage"},"image":{"@id":"https:\/\/www.valpiccola.it\/en\/2014\/07\/23\/slackline-paradise\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/07\/Banner_FB_event-600x222.jpg","datePublished":"2014-07-23T14:34:41+00:00","dateModified":"2014-07-23T14:34:41+00:00","author":{"@id":"https:\/\/www.valpiccola.it\/en\/#\/schema\/person\/290c27b7ec1ff98c207848f3e27dd912"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valpiccola.it\/en\/2014\/07\/23\/slackline-paradise\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.valpiccola.it\/en\/2014\/07\/23\/slackline-paradise\/#primaryimage","url":"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/07\/Banner_FB_event-600x222.jpg","contentUrl":"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2014\/07\/Banner_FB_event-600x222.jpg"},{"@type":"WebSite","@id":"https:\/\/www.valpiccola.it\/en\/#website","url":"https:\/\/www.valpiccola.it\/en\/","name":"Residence Valpiccola","description":"Holydays in the Dolomites  in val di Zoldo - Apartments, Residence, Garni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valpiccola.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.valpiccola.it\/en\/#\/schema\/person\/290c27b7ec1ff98c207848f3e27dd912","name":"Gianni Nobile","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.valpiccola.it\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a580b3bd64279503e913ad1edd9f52f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a580b3bd64279503e913ad1edd9f52f7?s=96&d=mm&r=g","caption":"Gianni Nobile"},"url":"https:\/\/www.valpiccola.it\/en\/author\/gianni-nobile-2\/"}]}},"_links":{"self":[{"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/posts\/1356"}],"collection":[{"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/users\/1001003"}],"replies":[{"embeddable":true,"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/comments?post=1356"}],"version-history":[{"count":1,"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/posts\/1356\/revisions"}],"predecessor-version":[{"id":1367,"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/posts\/1356\/revisions\/1367"}],"wp:attachment":[{"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/media?parent=1356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/categories?post=1356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.valpiccola.it\/en\/wp-json\/wp\/v2\/tags?post=1356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}