{"id":3409,"date":"2016-05-18T18:28:26","date_gmt":"2016-05-18T16:28:26","guid":{"rendered":"https:\/\/www.valpiccola.it\/?p=3409"},"modified":"2016-05-18T18:28:26","modified_gmt":"2016-05-18T16:28:26","slug":"dolomiti-extreme-trail-2016","status":"publish","type":"post","link":"https:\/\/www.valpiccola.it\/de\/2016\/05\/18\/dolomiti-extreme-trail-2016\/","title":{"rendered":"Dolomiti Extreme Trail 2016"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-3410 size-medium alignleft\" src=\"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2016\/05\/dxt-221x300.jpg\" alt=\"dxt\" width=\"221\" height=\"300\" srcset=\"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2016\/05\/dxt-221x300.jpg 221w, https:\/\/www.valpiccola.it\/wp-content\/uploads\/2016\/05\/dxt.jpg 439w\" sizes=\"(max-width: 221px) 100vw, 221px\" \/>Mancano poco meno di 4 settimane a <a href=\"http:\/\/www.dolomitiextremetrail.com\/it\/\" target=\"_blank\"><strong>Dolomiti Extreme Trail<\/strong><\/a>, trail in alta montagna nel cuore delle Dolomiti della Val di Zoldo. La gara, che prender\u00e0 il via il giorno 11 giugno 2016, propone tre diversi percorsi, che metteranno alla prova atleti provenienti da tutte le parti del mondo: il classico percorso di 53 km, un percorso pi\u00f9 breve di 23 km e, a partire da questa edizione, il percorso di 103 km, con un dislivello positivo di 7150 m e negativo di 7060 m.<\/p>\n<p>Al Residence Valpiccola, a circa 6 km dalla partenza del percorso di 23 km, gli ultimi appartamenti sono ancora liberi! Vi aspettiamo!<\/p>\n<p>Per info e prenotazioni contattateci:<\/p>\n<p><strong><a href=\"mailto:info@valpiccola.it\">info@valpiccola.it<\/a> &#8211; 0039 0437 788827<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mancano poco meno di 4 settimane a Dolomiti Extreme Trail, trail in alta<\/p>\n","protected":false},"author":1001003,"featured_media":3410,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[15],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dolomiti Extreme Trail 2016 - Residence and SPA Resort Valpiccola<\/title>\n<meta name=\"description\" content=\"Al Residence Valpiccola, a circa 6 km dalla partenza del percorso di 23 km, gli ultimi appartamenti sono ancora liberi! info@valpiccola.it - 0039 0437 788827\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.valpiccola.it\/de\/2016\/05\/18\/dolomiti-extreme-trail-2016\/\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianni Nobile\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.valpiccola.it\/de\/2016\/05\/18\/dolomiti-extreme-trail-2016\/\",\"url\":\"https:\/\/www.valpiccola.it\/de\/2016\/05\/18\/dolomiti-extreme-trail-2016\/\",\"name\":\"Dolomiti Extreme Trail 2016 - Residence and SPA Resort Valpiccola\",\"isPartOf\":{\"@id\":\"https:\/\/www.valpiccola.it\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.valpiccola.it\/de\/2016\/05\/18\/dolomiti-extreme-trail-2016\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.valpiccola.it\/de\/2016\/05\/18\/dolomiti-extreme-trail-2016\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2016\/05\/dxt.jpg\",\"datePublished\":\"2016-05-18T16:28:26+00:00\",\"dateModified\":\"2016-05-18T16:28:26+00:00\",\"author\":{\"@id\":\"https:\/\/www.valpiccola.it\/de\/#\/schema\/person\/290c27b7ec1ff98c207848f3e27dd912\"},\"description\":\"Al Residence Valpiccola, a circa 6 km dalla partenza del percorso di 23 km, gli ultimi appartamenti sono ancora liberi! info@valpiccola.it - 0039 0437 788827\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.valpiccola.it\/de\/2016\/05\/18\/dolomiti-extreme-trail-2016\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.valpiccola.it\/de\/2016\/05\/18\/dolomiti-extreme-trail-2016\/#primaryimage\",\"url\":\"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2016\/05\/dxt.jpg\",\"contentUrl\":\"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2016\/05\/dxt.jpg\",\"width\":439,\"height\":597},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.valpiccola.it\/de\/#website\",\"url\":\"https:\/\/www.valpiccola.it\/de\/\",\"name\":\"Residence and SPA Resort Valpiccola\",\"description\":\"Vacanze nelle Dolomiti in val di Zoldo - Appartamenti Residence Garni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.valpiccola.it\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.valpiccola.it\/de\/#\/schema\/person\/290c27b7ec1ff98c207848f3e27dd912\",\"name\":\"Gianni Nobile\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.valpiccola.it\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a580b3bd64279503e913ad1edd9f52f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a580b3bd64279503e913ad1edd9f52f7?s=96&d=mm&r=g\",\"caption\":\"Gianni Nobile\"},\"url\":\"https:\/\/www.valpiccola.it\/de\/author\/gianni-nobile-2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dolomiti Extreme Trail 2016 - Residence and SPA Resort Valpiccola","description":"Al Residence Valpiccola, a circa 6 km dalla partenza del percorso di 23 km, gli ultimi appartamenti sono ancora liberi! info@valpiccola.it - 0039 0437 788827","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valpiccola.it\/de\/2016\/05\/18\/dolomiti-extreme-trail-2016\/","twitter_misc":{"Verfasst von":"Gianni Nobile","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.valpiccola.it\/de\/2016\/05\/18\/dolomiti-extreme-trail-2016\/","url":"https:\/\/www.valpiccola.it\/de\/2016\/05\/18\/dolomiti-extreme-trail-2016\/","name":"Dolomiti Extreme Trail 2016 - Residence and SPA Resort Valpiccola","isPartOf":{"@id":"https:\/\/www.valpiccola.it\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valpiccola.it\/de\/2016\/05\/18\/dolomiti-extreme-trail-2016\/#primaryimage"},"image":{"@id":"https:\/\/www.valpiccola.it\/de\/2016\/05\/18\/dolomiti-extreme-trail-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2016\/05\/dxt.jpg","datePublished":"2016-05-18T16:28:26+00:00","dateModified":"2016-05-18T16:28:26+00:00","author":{"@id":"https:\/\/www.valpiccola.it\/de\/#\/schema\/person\/290c27b7ec1ff98c207848f3e27dd912"},"description":"Al Residence Valpiccola, a circa 6 km dalla partenza del percorso di 23 km, gli ultimi appartamenti sono ancora liberi! info@valpiccola.it - 0039 0437 788827","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valpiccola.it\/de\/2016\/05\/18\/dolomiti-extreme-trail-2016\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.valpiccola.it\/de\/2016\/05\/18\/dolomiti-extreme-trail-2016\/#primaryimage","url":"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2016\/05\/dxt.jpg","contentUrl":"https:\/\/www.valpiccola.it\/wp-content\/uploads\/2016\/05\/dxt.jpg","width":439,"height":597},{"@type":"WebSite","@id":"https:\/\/www.valpiccola.it\/de\/#website","url":"https:\/\/www.valpiccola.it\/de\/","name":"Residence and SPA Resort Valpiccola","description":"Vacanze nelle Dolomiti in val di Zoldo - Appartamenti Residence Garni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valpiccola.it\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.valpiccola.it\/de\/#\/schema\/person\/290c27b7ec1ff98c207848f3e27dd912","name":"Gianni Nobile","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.valpiccola.it\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a580b3bd64279503e913ad1edd9f52f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a580b3bd64279503e913ad1edd9f52f7?s=96&d=mm&r=g","caption":"Gianni Nobile"},"url":"https:\/\/www.valpiccola.it\/de\/author\/gianni-nobile-2\/"}]}},"_links":{"self":[{"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/posts\/3409"}],"collection":[{"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/users\/1001003"}],"replies":[{"embeddable":true,"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/comments?post=3409"}],"version-history":[{"count":3,"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/posts\/3409\/revisions"}],"predecessor-version":[{"id":3421,"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/posts\/3409\/revisions\/3421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/media\/3410"}],"wp:attachment":[{"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/media?parent=3409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/categories?post=3409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/tags?post=3409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}