{"id":1130,"date":"2013-03-29T16:13:58","date_gmt":"2013-03-29T14:13:58","guid":{"rendered":"https:\/\/www.valpiccola.it\/?p=1130"},"modified":"2013-03-29T16:14:51","modified_gmt":"2013-03-29T14:14:51","slug":"splash-party","status":"publish","type":"post","link":"https:\/\/www.valpiccola.it\/de\/2013\/03\/29\/splash-party\/","title":{"rendered":"Splash Party!"},"content":{"rendered":"<p>La festa di chiusura pi\u00f9 cool che ci sia&#8230; In \u00a0una parola SPLASH PARTY!<br \/>\nL\u2019evento, giunto alla sua 5a edizione, sull\u2019onda del successo e dell\u2019entusiasmo ottenuto nelle stagioni passate, andr\u00e0 in scena il\u00a0<strong>luned\u00ec\u00a0<\/strong>di\u00a0<strong>Pasquetta<\/strong>, il\u00a0<strong>1 aprile<\/strong>, in localit\u00e0\u00a0<strong>Piani di Pezz\u00e8<\/strong>, ad\u00a0<strong>Alleghe<\/strong>, dove sar\u00e0 allestita una piscina lunga 30 metri.<\/p>\n<p>&nbsp;<\/p>\n<p>La festa avr\u00e0 inizio alle ore 9.30 e si continuer\u00e0 tra musica con DJ, spettacolo e tanto divertimento. L\u2019obiettivo per i partecipanti dello Splash Party sar\u00e0 quello di affrontare e attraversare la piscina con ogni mezzo possibile. Tutti sono invitati a partecipare, l\u2019iscrizione \u00e8 gratuita, basta solo un po\u2019 di spirito goliardico, tanta voglia di divertirsi e poca paura di bagnarsi.<br \/>\nPer l\u2019allestimento degli equipaggi e dei mezzi gli organizzatori hanno suggerito come traccia da seguire il tema\u00a0<strong>\u201cl\u2019origine della specie\u201d<\/strong>.<br \/>\nNell\u2019ordine i primi a scendere, ad affrontare il tentativo di attraversamento della piscina,\u00a0 saranno i mezzi leggeri come sci, snowboard, telemark e poi via via a seguire tutti gli altri mezzi.<\/p>\n<p>Oltre alla piscina ci sar\u00e0 spazio anche per l\u2019iniziativa\u00a0<strong><em>\u201cI\u2019am a kamikaze again\u201d\u00a0<\/em><\/strong>con il salto dalla pedana nel big air bag (in funzione dalle 10.30 alle 15.00), una novit\u00e0 in pi\u00f9 per il divertimento di tutti i presenti.<\/p>\n<p>&nbsp;<\/p>\n<p>Alle ore 17.00 ci saranno le premiazioni con tanti gadget per tutti e poi si continuer\u00e0 a fare festa fino a notte inoltrata dando l\u2019arrivederci all\u2019inverno 2012-2013 e il benvenuto alla bella stagione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La festa di chiusura pi\u00f9 cool che ci sia&#8230; In \u00a0una parola SPLASH<\/p>\n","protected":false},"author":1001003,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[15],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Splash Party! - Residence and SPA Resort Valpiccola<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.valpiccola.it\/de\/2013\/03\/29\/splash-party\/\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianni Nobile\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.valpiccola.it\/de\/2013\/03\/29\/splash-party\/\",\"url\":\"https:\/\/www.valpiccola.it\/de\/2013\/03\/29\/splash-party\/\",\"name\":\"Splash Party! - Residence and SPA Resort Valpiccola\",\"isPartOf\":{\"@id\":\"https:\/\/www.valpiccola.it\/de\/#website\"},\"datePublished\":\"2013-03-29T14:13:58+00:00\",\"dateModified\":\"2013-03-29T14:14:51+00:00\",\"author\":{\"@id\":\"https:\/\/www.valpiccola.it\/de\/#\/schema\/person\/290c27b7ec1ff98c207848f3e27dd912\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.valpiccola.it\/de\/2013\/03\/29\/splash-party\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.valpiccola.it\/de\/#website\",\"url\":\"https:\/\/www.valpiccola.it\/de\/\",\"name\":\"Residence and SPA Resort Valpiccola\",\"description\":\"Vacanze nelle Dolomiti in val di Zoldo - Appartamenti Residence Garni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.valpiccola.it\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.valpiccola.it\/de\/#\/schema\/person\/290c27b7ec1ff98c207848f3e27dd912\",\"name\":\"Gianni Nobile\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.valpiccola.it\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a580b3bd64279503e913ad1edd9f52f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a580b3bd64279503e913ad1edd9f52f7?s=96&d=mm&r=g\",\"caption\":\"Gianni Nobile\"},\"url\":\"https:\/\/www.valpiccola.it\/de\/author\/gianni-nobile-2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Splash Party! - Residence and SPA Resort Valpiccola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valpiccola.it\/de\/2013\/03\/29\/splash-party\/","twitter_misc":{"Verfasst von":"Gianni Nobile","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.valpiccola.it\/de\/2013\/03\/29\/splash-party\/","url":"https:\/\/www.valpiccola.it\/de\/2013\/03\/29\/splash-party\/","name":"Splash Party! - Residence and SPA Resort Valpiccola","isPartOf":{"@id":"https:\/\/www.valpiccola.it\/de\/#website"},"datePublished":"2013-03-29T14:13:58+00:00","dateModified":"2013-03-29T14:14:51+00:00","author":{"@id":"https:\/\/www.valpiccola.it\/de\/#\/schema\/person\/290c27b7ec1ff98c207848f3e27dd912"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valpiccola.it\/de\/2013\/03\/29\/splash-party\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.valpiccola.it\/de\/#website","url":"https:\/\/www.valpiccola.it\/de\/","name":"Residence and SPA Resort Valpiccola","description":"Vacanze nelle Dolomiti in val di Zoldo - Appartamenti Residence Garni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valpiccola.it\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.valpiccola.it\/de\/#\/schema\/person\/290c27b7ec1ff98c207848f3e27dd912","name":"Gianni Nobile","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.valpiccola.it\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a580b3bd64279503e913ad1edd9f52f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a580b3bd64279503e913ad1edd9f52f7?s=96&d=mm&r=g","caption":"Gianni Nobile"},"url":"https:\/\/www.valpiccola.it\/de\/author\/gianni-nobile-2\/"}]}},"_links":{"self":[{"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/posts\/1130"}],"collection":[{"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/users\/1001003"}],"replies":[{"embeddable":true,"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/comments?post=1130"}],"version-history":[{"count":1,"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/posts\/1130\/revisions"}],"predecessor-version":[{"id":1132,"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/posts\/1130\/revisions\/1132"}],"wp:attachment":[{"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/media?parent=1130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/categories?post=1130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.valpiccola.it\/de\/wp-json\/wp\/v2\/tags?post=1130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}